{"id":5187,"date":"2016-05-24T12:53:35","date_gmt":"2016-05-24T10:53:35","guid":{"rendered":"https:\/\/www.gjh.de\/frog\/?p=5187"},"modified":"2016-07-14T14:26:33","modified_gmt":"2016-07-14T12:26:33","slug":"gruene-jugend-hessen-waehlt-neuen-landesvorstand","status":"publish","type":"post","link":"https:\/\/www.gjh.de\/frog\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\/","title":{"rendered":"Gr\u00fcne Jugend Hessen w\u00e4hlt neuen Landesvorstand"},"content":{"rendered":"<p>Am 21. und 22. Mai hat die Gr\u00fcne Jugend Hessen (GJH) in Wiesbaden ihre Landesmitgliederversammlung abgehalten und dabei einen neuen Landesvorstand gew\u00e4hlt.<\/p>\n<p>Frisch gebackene Landesvorsitzende der Jugendorganisation des hessischen Landesverbands der Partei B\u00fcndnis 90\/Die Gr\u00fcnen ist die 21-j\u00e4hrige Sarah von Hagen aus Diemelsee, die bislang als Beisitzerin im Vorstand t\u00e4tig war. Sie studiert Deutsch &amp; Geschichte. Seit 2013 ist sie Vorsitzende der Gr\u00fcnen Jugend Waldeck-Frankenberg und seit 2015 Beisitzerin im Vorstand der Gr\u00fcnen Waldeck-Frankenberg.\u00a0Der 22-j\u00e4hrige Thorben S\u00e4mann wurde in seinem Amt als Vorsitzender der GJH best\u00e4tigt. Er studiert Zahnmedizin und kommt aus dem Kreisverband Lahn-Dill.\u00a0 Auch die frauenpolitische Sprecherin Ann-Christine Herbold, eine 19-j\u00e4hrige Lehramtsstudentin (Englisch &amp; Geschichte), sowie der Landesschatzmeister Felix Martin, ein 20-j\u00e4hriger Student der Soziologie und Politikwissenschaften, beide aus dem Werra-Mei\u00dfner-Kreis, wurden von der Versammlung wiedergew\u00e4hlt. Neu dabei sind die drei Beisitzer*innen Elena Sch\u00f6rling, eine 18-j\u00e4hrige Sch\u00fclerin aus Kassel, Maximilian Walz, ein 21-j\u00e4hriger Lehramtsstudent (Politik &amp; Sport) aus Marburg und die 19-j\u00e4hrige Lehramtsstudentin (Politik &amp; Informatik) Anika Schm\u00fctz aus Darmstadt.<\/p>\n<p>Die Schwerpunktthemen der Landesmitgliederversammlung der GJH bildeten Netzpolitik, Datenschutz, Digitalisierung, Netzfeminismus und neue Technologien. Dazu wurde eine umfangreiche Beschlusslage getroffen. So will die GJH beispielsweise das E-Learning st\u00e4rken, die mediale Ausstattung an Schulen verbessern, eine fl\u00e4chendeckende Versorgung mit Breitband-Internet sicherstellen und das sogenannte E-Government ausbauen, also zum Beispiel die M\u00f6glichkeit er\u00f6ffnen Beh\u00f6rdeng\u00e4nge im Internet zu erledigen. Dabei setzt die Jugendorganisation jedoch auf die Gew\u00e4hrleistung hoher Datenschutzstandards<\/p>\n<p>Dar\u00fcber hinaus fordern die Nachwuchspolitiker*innen eine noch konsequentere Energiewende, starke B\u00fcrger*innenbeteiligung bei geplanten Windkraftanlagen und einen gr\u00f6\u00dferen politischen Fokus auf das Thema Elektromobilit\u00e4t. Deutsche Waffenexporte sollen stark beschr\u00e4nkt werden und die umstrittenen Freihandelsabkommen TTIP und CETA sowie das Dienstleistungsabkommen TISA lehnt die Gr\u00fcne Jugend Hessen ab. Die GJH unterst\u00fctzt au\u00dferdem die j\u00fcngste Forderung der hessischen Landessch\u00fclervertretung, klassische Hausaufgaben langfristig abzuschaffen und durch bessere Nachmittagsbetreuung sowie flexible Ganztagsschulen zu ersetzen. Dar\u00fcber hinaus spricht sich die GJH noch einmal ausdr\u00fccklich f\u00fcr einen starken, friedlichen Protest gegen die AfD sowie mit ihr zusammenh\u00e4ngende Verb\u00e4nde und Gruppierungen aus.<\/p>\n<p>Mit Daniel May, Martina Feldmayer und Matthias Wagner waren auch drei Landtagsabgeordnete zu Gast. Mit dem Vorsitzenden der Gr\u00fcnen Landtagsfraktion, Matthias Wagner, und der Sprecherin der Gr\u00fcnen Jugend Baden-W\u00fcrttemberg, Leonie Wolf, diskutierten die Mitglieder am Samstagabend au\u00dferdem, ob eine Koalition aus CDU und Gr\u00fcnen f\u00fcr die Bundestagswahl 2017 denkbar w\u00e4re. In Hessen arbeitet diese ungew\u00f6hnliche Koalition bereits seit \u00fcber zwei Jahren gut zusammen, wie Wagner betonte; in Baden-W\u00fcrttemberg hat sich nach dem sensationellen Wahlerfolg der heimischen Gr\u00fcnen eine gr\u00fcn-schwarze Regierung unter dem Gr\u00fcnen Ministerpr\u00e4sidenten Winfried Kretschmann gebildet<\/p>\n<p>Bereits in zwei Wochen tritt die Gr\u00fcne Jugend Hessen dann zu einer nicht weniger wichtigen Versammlung zusammen. Dann wird sie f\u00fcr die anstehende Bundestagswahl ihr Votum an eine Kandidatin bzw. einen Kandidaten aus den eigenen Reihen vergeben. Dass dieses junggr\u00fcne Votum gro\u00dfe Relevanz haben kann, beweisen Nicole Maisch und Omid Nouripour, beide ehemalige Vorsitzende der Gr\u00fcnen Jugend Hessen und heute etablierte Politiker*innen der Gr\u00fcnen Bundestagsfraktion.<\/p>\n<div id=\"attachment_5132\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.gjh.de\/frog\/wp-content\/uploads\/LavoWebsite.jpg\" rel=\"attachment wp-att-5132\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5132\" class=\"wp-image-5132 size-medium\" src=\"https:\/\/www.gjh.de\/frog\/wp-content\/uploads\/LavoWebsite-300x200.jpg\" alt=\"v.l,n.r.: Ann-Christine Herbold, Nina Eisenhardt, Felix Martin, Elena Sch\u00f6rling, Sarah von Hagen, Thorben S\u00e4mann, Anika Schm\u00fctz, Maximilian Walz\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.gjh.de\/frog\/wp-content\/uploads\/LavoWebsite-300x200.jpg 300w, https:\/\/www.gjh.de\/frog\/wp-content\/uploads\/LavoWebsite-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-5132\" class=\"wp-caption-text\">v.l.n.r.: Ann-Christine Herbold, Nina Eisenhardt, Felix Martin, Elena Sch\u00f6rling, Sarah von Hagen, Thorben S\u00e4mann, Anika Schm\u00fctz, Maximilian Walz<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Am 21. und 22. Mai hat die Gr\u00fcne Jugend Hessen (GJH) in Wiesbaden ihre Landesmitgliederversammlung abgehalten und dabei einen neuen Landesvorstand gew\u00e4hlt. Frisch gebackene Landesvorsitzende der Jugendorganisation des hessischen Landesverbands der Partei B\u00fcndnis 90\/Die Gr\u00fcnen ist die 21-j\u00e4hrige Sarah von Hagen aus Diemelsee, die bislang als Beisitzerin im Vorstand t\u00e4tig war. Sie studiert Deutsch &amp; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,7,3,5],"tags":[],"class_list":["post-5187","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-lavo","category-nachrichten","category-pressemitteilungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gr\u00fcne Jugend Hessen w\u00e4hlt neuen Landesvorstand - GR\u00dcNE JUGEND Hessen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gjh.de\/frog\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gr\u00fcne Jugend Hessen w\u00e4hlt neuen Landesvorstand - GR\u00dcNE JUGEND Hessen\" \/>\n<meta property=\"og:description\" content=\"Am 21. und 22. Mai hat die Gr\u00fcne Jugend Hessen (GJH) in Wiesbaden ihre Landesmitgliederversammlung abgehalten und dabei einen neuen Landesvorstand gew\u00e4hlt. Frisch gebackene Landesvorsitzende der Jugendorganisation des hessischen Landesverbands der Partei B\u00fcndnis 90\/Die Gr\u00fcnen ist die 21-j\u00e4hrige Sarah von Hagen aus Diemelsee, die bislang als Beisitzerin im Vorstand t\u00e4tig war. Sie studiert Deutsch &amp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gjh.de\/frog\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\/\" \/>\n<meta property=\"og:site_name\" content=\"GR\u00dcNE JUGEND Hessen\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-24T10:53:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-14T12:26:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gjh.de\/frog\/wp-content\/uploads\/LavoWebsite-300x200.jpg\" \/>\n<meta name=\"author\" content=\"Gr\u00fcne Jugend Hessen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gr\u00fcne Jugend Hessen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\\\/\"},\"author\":{\"name\":\"Gr\u00fcne Jugend Hessen\",\"@id\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/#\\\/schema\\\/person\\\/b8fa006520a86a3226e05402520d4f13\"},\"headline\":\"Gr\u00fcne Jugend Hessen w\u00e4hlt neuen Landesvorstand\",\"datePublished\":\"2016-05-24T10:53:35+00:00\",\"dateModified\":\"2016-07-14T12:26:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\\\/\"},\"wordCount\":575,\"image\":{\"@id\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/wp-content\\\/uploads\\\/LavoWebsite-300x200.jpg\",\"articleSection\":{\"1\":\"Landesvorstand\",\"2\":\"Nachrichten\",\"3\":\"Pressemitteilungen\"},\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\\\/\",\"url\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\\\/\",\"name\":\"Gr\u00fcne Jugend Hessen w\u00e4hlt neuen Landesvorstand - GR\u00dcNE JUGEND Hessen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/wp-content\\\/uploads\\\/LavoWebsite-300x200.jpg\",\"datePublished\":\"2016-05-24T10:53:35+00:00\",\"dateModified\":\"2016-07-14T12:26:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/#\\\/schema\\\/person\\\/b8fa006520a86a3226e05402520d4f13\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gjh.de\\\/frog\\\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/wp-content\\\/uploads\\\/LavoWebsite.jpg\",\"contentUrl\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/wp-content\\\/uploads\\\/LavoWebsite.jpg\",\"width\":4648,\"height\":3099,\"caption\":\"v.l,n.r.: Ann-Christine Herbold, Nina Eisenhardt, Felix Martin, Elena Sch\u00f6rling, Sarah von Hagen, Thorben S\u00e4mann, Anika Schm\u00fctz, Maximilian Walz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gr\u00fcne Jugend Hessen w\u00e4hlt neuen Landesvorstand\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/#website\",\"url\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/\",\"name\":\"GR\u00dcNE JUGEND Hessen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/#\\\/schema\\\/person\\\/b8fa006520a86a3226e05402520d4f13\",\"name\":\"Gr\u00fcne Jugend Hessen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e938d46263c3d10a08350877687bfc15fd4ba70a3de2fa88ac7b3d8603f2ed56?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e938d46263c3d10a08350877687bfc15fd4ba70a3de2fa88ac7b3d8603f2ed56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e938d46263c3d10a08350877687bfc15fd4ba70a3de2fa88ac7b3d8603f2ed56?s=96&d=mm&r=g\",\"caption\":\"Gr\u00fcne Jugend Hessen\"},\"sameAs\":[\"https:\\\/\\\/www.gjh.de\"],\"url\":\"https:\\\/\\\/www.gjh.de\\\/frog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gr\u00fcne Jugend Hessen w\u00e4hlt neuen Landesvorstand - GR\u00dcNE JUGEND Hessen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gjh.de\/frog\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\/","og_locale":"de_DE","og_type":"article","og_title":"Gr\u00fcne Jugend Hessen w\u00e4hlt neuen Landesvorstand - GR\u00dcNE JUGEND Hessen","og_description":"Am 21. und 22. Mai hat die Gr\u00fcne Jugend Hessen (GJH) in Wiesbaden ihre Landesmitgliederversammlung abgehalten und dabei einen neuen Landesvorstand gew\u00e4hlt. Frisch gebackene Landesvorsitzende der Jugendorganisation des hessischen Landesverbands der Partei B\u00fcndnis 90\/Die Gr\u00fcnen ist die 21-j\u00e4hrige Sarah von Hagen aus Diemelsee, die bislang als Beisitzerin im Vorstand t\u00e4tig war. Sie studiert Deutsch &amp; [&hellip;]","og_url":"https:\/\/www.gjh.de\/frog\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\/","og_site_name":"GR\u00dcNE JUGEND Hessen","article_published_time":"2016-05-24T10:53:35+00:00","article_modified_time":"2016-07-14T12:26:33+00:00","og_image":[{"url":"https:\/\/www.gjh.de\/frog\/wp-content\/uploads\/LavoWebsite-300x200.jpg","type":"","width":"","height":""}],"author":"Gr\u00fcne Jugend Hessen","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Gr\u00fcne Jugend Hessen","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gjh.de\/frog\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\/#article","isPartOf":{"@id":"https:\/\/www.gjh.de\/frog\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\/"},"author":{"name":"Gr\u00fcne Jugend Hessen","@id":"https:\/\/www.gjh.de\/frog\/#\/schema\/person\/b8fa006520a86a3226e05402520d4f13"},"headline":"Gr\u00fcne Jugend Hessen w\u00e4hlt neuen Landesvorstand","datePublished":"2016-05-24T10:53:35+00:00","dateModified":"2016-07-14T12:26:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gjh.de\/frog\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\/"},"wordCount":575,"image":{"@id":"https:\/\/www.gjh.de\/frog\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gjh.de\/frog\/wp-content\/uploads\/LavoWebsite-300x200.jpg","articleSection":{"1":"Landesvorstand","2":"Nachrichten","3":"Pressemitteilungen"},"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.gjh.de\/frog\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\/","url":"https:\/\/www.gjh.de\/frog\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\/","name":"Gr\u00fcne Jugend Hessen w\u00e4hlt neuen Landesvorstand - GR\u00dcNE JUGEND Hessen","isPartOf":{"@id":"https:\/\/www.gjh.de\/frog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gjh.de\/frog\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\/#primaryimage"},"image":{"@id":"https:\/\/www.gjh.de\/frog\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gjh.de\/frog\/wp-content\/uploads\/LavoWebsite-300x200.jpg","datePublished":"2016-05-24T10:53:35+00:00","dateModified":"2016-07-14T12:26:33+00:00","author":{"@id":"https:\/\/www.gjh.de\/frog\/#\/schema\/person\/b8fa006520a86a3226e05402520d4f13"},"breadcrumb":{"@id":"https:\/\/www.gjh.de\/frog\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gjh.de\/frog\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.gjh.de\/frog\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\/#primaryimage","url":"https:\/\/www.gjh.de\/frog\/wp-content\/uploads\/LavoWebsite.jpg","contentUrl":"https:\/\/www.gjh.de\/frog\/wp-content\/uploads\/LavoWebsite.jpg","width":4648,"height":3099,"caption":"v.l,n.r.: Ann-Christine Herbold, Nina Eisenhardt, Felix Martin, Elena Sch\u00f6rling, Sarah von Hagen, Thorben S\u00e4mann, Anika Schm\u00fctz, Maximilian Walz"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gjh.de\/frog\/gruene-jugend-hessen-waehlt-neuen-landesvorstand\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.gjh.de\/frog\/"},{"@type":"ListItem","position":2,"name":"Gr\u00fcne Jugend Hessen w\u00e4hlt neuen Landesvorstand"}]},{"@type":"WebSite","@id":"https:\/\/www.gjh.de\/frog\/#website","url":"https:\/\/www.gjh.de\/frog\/","name":"GR\u00dcNE JUGEND Hessen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gjh.de\/frog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.gjh.de\/frog\/#\/schema\/person\/b8fa006520a86a3226e05402520d4f13","name":"Gr\u00fcne Jugend Hessen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e938d46263c3d10a08350877687bfc15fd4ba70a3de2fa88ac7b3d8603f2ed56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e938d46263c3d10a08350877687bfc15fd4ba70a3de2fa88ac7b3d8603f2ed56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e938d46263c3d10a08350877687bfc15fd4ba70a3de2fa88ac7b3d8603f2ed56?s=96&d=mm&r=g","caption":"Gr\u00fcne Jugend Hessen"},"sameAs":["https:\/\/www.gjh.de"],"url":"https:\/\/www.gjh.de\/frog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gjh.de\/frog\/wp-json\/wp\/v2\/posts\/5187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gjh.de\/frog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gjh.de\/frog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gjh.de\/frog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gjh.de\/frog\/wp-json\/wp\/v2\/comments?post=5187"}],"version-history":[{"count":4,"href":"https:\/\/www.gjh.de\/frog\/wp-json\/wp\/v2\/posts\/5187\/revisions"}],"predecessor-version":[{"id":5191,"href":"https:\/\/www.gjh.de\/frog\/wp-json\/wp\/v2\/posts\/5187\/revisions\/5191"}],"wp:attachment":[{"href":"https:\/\/www.gjh.de\/frog\/wp-json\/wp\/v2\/media?parent=5187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gjh.de\/frog\/wp-json\/wp\/v2\/categories?post=5187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gjh.de\/frog\/wp-json\/wp\/v2\/tags?post=5187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}